{"id":4299,"date":"2023-05-19T21:30:17","date_gmt":"2023-05-19T21:30:17","guid":{"rendered":"https:\/\/unrostore.com\/?post_type=product&#038;p=4299"},"modified":"2026-01-19T20:37:25","modified_gmt":"2026-01-19T20:37:25","slug":"amazonia-gruner-krug","status":"publish","type":"product","link":"https:\/\/unrostore.com\/de-at\/shop\/dekoration-2\/vasen\/amazonia-gruner-krug\/","title":{"rendered":"Gr\u00fcner Krug Amazonien Green"},"content":{"rendered":"<h3>Entdecken Sie die Vielseitigkeit der einzigartigen gr\u00fcner Krug Amazonia Green<\/h3>\n<p>Die <strong>Gr\u00fcner Krug<\/strong> Amazonia Green von <a href=\"https:\/\/www.terrafinastore.com\/en\/collections\/coffee\">Terrafina<\/a> wird aus handgefertigter Keramik aus Portugal hergestellt. Entdecken Sie die Bequemlichkeit dieses sch\u00f6nen Wasserkruges aus der Amazonia Green Geschirrkollektion. Spa\u00df als Geschenk zu geben, f\u00fcr einen Geburtstag, sondern auch praktisch, um selbst zu verwenden. Sch\u00f6n in Ihrem Interieur als gr\u00fcne Vase f\u00fcr Ihre frischen Blumen, als Tulpenvase. Ideal auch zum Einschenken eines k\u00fchlen Getr\u00e4nks bei einem gem\u00fctlichen Abendessen, Picknick, Lunch oder Dinner. Der Wasserkrug ist sehr vielseitig und kann sicherlich auch als Sangria-Krug oder Weinkrug verwendet werden! Schaffen Sie Einheit am Tisch und kombinieren Sie den Keramikkrug mit dem gr\u00fcnen <a href=\"https:\/\/unrostore.com\/de-at\/shop\/terrafina\/amazonia-grun\/groen-serviesset-pastaborden-amazonia-green\/\">Geschirrset mit Nudeltellern<\/a> ob die <a href=\"https:\/\/unrostore.com\/de-at\/shop\/terrafina\/amazonia-grun\/groen-serviesset-amazonia-green-4-personen\/\">Geschirrset mit Sch\u00fcsseln<\/a>. Genie\u00dfen Sie jeden Tag mit dem gr\u00fcnen Geschirr aus der Amazonia-Geschirrkollektion!<\/p>\n<h3>Dies ist die Nummer, die Sie zugestellt bekommen<\/h3>\n<ul>\n<li>1x Krug Amazonia Green 1.8L<\/li>\n<li>1x Terrafina Geschenkbox<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em><strong>Nachhaltig f\u00fcr Mensch und Umwelt:<\/strong><br \/>\nJedes Produkt ist ein Unikat, denn es wird in Handarbeit hergestellt.<br \/>\nDruck und Textur k\u00f6nnen daher leicht vom Produktfoto abweichen.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<div class=\"usps\"><i class=\"far fa-check-circle\"><\/i> Mikrowellenfest<br \/>\n<i class=\"far fa-check-circle\"><\/i> Backofenfest (bis zu 200 Grad)<br \/>\n<i class=\"far fa-check-circle\"><\/i> Sp\u00fclmaschinentauglich<br \/>\n<i class=\"far fa-thumbs-up\"><\/i> Handgefertigt<\/div>","protected":false},"featured_media":6741,"template":"","meta":[],"product_brand":[],"product_cat":[869,273,170,119,212],"product_tag":[173,171,410,758,388,755,756,389,759,757,754,760],"class_list":{"0":"post-4299","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-unro-cadeautips","7":"product_cat-decoratie","8":"product_cat-amazonia-green","9":"product_cat-terrafina","10":"product_cat-vazen","11":"product_tag-amazonia-green","12":"product_tag-groen","13":"product_tag-groene-kan","14":"product_tag-groene-vaas","15":"product_tag-kan","16":"product_tag-sangria-kan","17":"product_tag-sangriakan","18":"product_tag-serveerkan","19":"product_tag-tulpenvaas","20":"product_tag-water-kan","21":"product_tag-waterkan","22":"product_tag-wijnkan","23":"product_shipping_class-pakket","25":"first","26":"outofstock","27":"sale","28":"taxable","29":"shipping-taxable","30":"purchasable","31":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Groene Kan Amazonia Green &#8226; UNRO<\/title>\n<meta name=\"description\" content=\"De groene kan van handgemaakt keramiek is een perfecte aanvulling op jouw zwarte servies en erg handig voor water, sangria, bloemen of als cadeau!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unrostore.com\/de-at\/shop\/dekoration-2\/vasen\/amazonia-gruner-krug\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Groene Kan Amazonia Green &#8226; UNRO\" \/>\n<meta property=\"og:description\" content=\"De groene kan van handgemaakt keramiek is een perfecte aanvulling op jouw zwarte servies en erg handig voor water, sangria, bloemen of als cadeau!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unrostore.com\/de-at\/shop\/dekoration-2\/vasen\/amazonia-gruner-krug\/\" \/>\n<meta property=\"og:site_name\" content=\"UNRO\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T20:37:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unrostore.com\/wp-content\/uploads\/2023\/05\/unro-groene-kan-handgemaakt-keramiek.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/unrostore.com\\\/shop\\\/decoratie\\\/vazen\\\/groene-kan-amazonia-green\\\/\",\"url\":\"https:\\\/\\\/unrostore.com\\\/shop\\\/decoratie\\\/vazen\\\/groene-kan-amazonia-green\\\/\",\"name\":\"Groene Kan Amazonia Green &#8226; UNRO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unrostore.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/unrostore.com\\\/shop\\\/decoratie\\\/vazen\\\/groene-kan-amazonia-green\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/unrostore.com\\\/shop\\\/decoratie\\\/vazen\\\/groene-kan-amazonia-green\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unrostore.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/unro-groene-kan-handgemaakt-keramiek.webp\",\"datePublished\":\"2023-05-19T21:30:17+00:00\",\"dateModified\":\"2026-01-19T20:37:25+00:00\",\"description\":\"De groene kan van handgemaakt keramiek is een perfecte aanvulling op jouw zwarte servies en erg handig voor water, sangria, bloemen of als cadeau!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/unrostore.com\\\/shop\\\/decoratie\\\/vazen\\\/groene-kan-amazonia-green\\\/#breadcrumb\"},\"inLanguage\":\"de-AT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/unrostore.com\\\/shop\\\/decoratie\\\/vazen\\\/groene-kan-amazonia-green\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\\\/\\\/unrostore.com\\\/shop\\\/decoratie\\\/vazen\\\/groene-kan-amazonia-green\\\/#primaryimage\",\"url\":\"https:\\\/\\\/unrostore.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/unro-groene-kan-handgemaakt-keramiek.webp\",\"contentUrl\":\"https:\\\/\\\/unrostore.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/unro-groene-kan-handgemaakt-keramiek.webp\",\"width\":1000,\"height\":1000,\"caption\":\"groene kan handgemaakt keramiek\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/unrostore.com\\\/shop\\\/decoratie\\\/vazen\\\/groene-kan-amazonia-green\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/unrostore.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/unrostore.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Groene Kan Amazonia Green\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/unrostore.com\\\/#website\",\"url\":\"https:\\\/\\\/unrostore.com\\\/\",\"name\":\"UNRO\",\"description\":\"Portugees servies waar je blij van wordt!\",\"publisher\":{\"@id\":\"https:\\\/\\\/unrostore.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/unrostore.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-AT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/unrostore.com\\\/#organization\",\"name\":\"UNRO\",\"url\":\"https:\\\/\\\/unrostore.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\\\/\\\/unrostore.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/unrostore.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo-UNRO.png\",\"contentUrl\":\"https:\\\/\\\/unrostore.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo-UNRO.png\",\"width\":605,\"height\":179,\"caption\":\"UNRO\"},\"image\":{\"@id\":\"https:\\\/\\\/unrostore.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gr\u00fcner Krug Amazonien Gr\u00fcn - UNRO","description":"Der gr\u00fcne Krug aus handgefertigter Keramik ist eine perfekte Erg\u00e4nzung zu Ihrem schwarzen Geschirr und sehr praktisch f\u00fcr Wasser, Sangria, Blumen oder als Geschenk!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unrostore.com\/de-at\/shop\/dekoration-2\/vasen\/amazonia-gruner-krug\/","og_locale":"de_DE","og_type":"article","og_title":"Groene Kan Amazonia Green &#8226; UNRO","og_description":"De groene kan van handgemaakt keramiek is een perfecte aanvulling op jouw zwarte servies en erg handig voor water, sangria, bloemen of als cadeau!","og_url":"https:\/\/unrostore.com\/de-at\/shop\/dekoration-2\/vasen\/amazonia-gruner-krug\/","og_site_name":"UNRO","article_modified_time":"2026-01-19T20:37:25+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/unrostore.com\/wp-content\/uploads\/2023\/05\/unro-groene-kan-handgemaakt-keramiek.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/unrostore.com\/shop\/decoratie\/vazen\/groene-kan-amazonia-green\/","url":"https:\/\/unrostore.com\/shop\/decoratie\/vazen\/groene-kan-amazonia-green\/","name":"Gr\u00fcner Krug Amazonien Gr\u00fcn - UNRO","isPartOf":{"@id":"https:\/\/unrostore.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unrostore.com\/shop\/decoratie\/vazen\/groene-kan-amazonia-green\/#primaryimage"},"image":{"@id":"https:\/\/unrostore.com\/shop\/decoratie\/vazen\/groene-kan-amazonia-green\/#primaryimage"},"thumbnailUrl":"https:\/\/unrostore.com\/wp-content\/uploads\/2023\/05\/unro-groene-kan-handgemaakt-keramiek.webp","datePublished":"2023-05-19T21:30:17+00:00","dateModified":"2026-01-19T20:37:25+00:00","description":"Der gr\u00fcne Krug aus handgefertigter Keramik ist eine perfekte Erg\u00e4nzung zu Ihrem schwarzen Geschirr und sehr praktisch f\u00fcr Wasser, Sangria, Blumen oder als Geschenk!","breadcrumb":{"@id":"https:\/\/unrostore.com\/shop\/decoratie\/vazen\/groene-kan-amazonia-green\/#breadcrumb"},"inLanguage":"de-AT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unrostore.com\/shop\/decoratie\/vazen\/groene-kan-amazonia-green\/"]}]},{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/unrostore.com\/shop\/decoratie\/vazen\/groene-kan-amazonia-green\/#primaryimage","url":"https:\/\/unrostore.com\/wp-content\/uploads\/2023\/05\/unro-groene-kan-handgemaakt-keramiek.webp","contentUrl":"https:\/\/unrostore.com\/wp-content\/uploads\/2023\/05\/unro-groene-kan-handgemaakt-keramiek.webp","width":1000,"height":1000,"caption":"groene kan handgemaakt keramiek"},{"@type":"BreadcrumbList","@id":"https:\/\/unrostore.com\/shop\/decoratie\/vazen\/groene-kan-amazonia-green\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/unrostore.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/unrostore.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Groene Kan Amazonia Green"}]},{"@type":"WebSite","@id":"https:\/\/unrostore.com\/#website","url":"https:\/\/unrostore.com\/","name":"UNRO","description":"Portugiesisches Geschirr, das Sie gl\u00fccklich machen wird!","publisher":{"@id":"https:\/\/unrostore.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unrostore.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-AT"},{"@type":"Organization","@id":"https:\/\/unrostore.com\/#organization","name":"UNRO","url":"https:\/\/unrostore.com\/","logo":{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/unrostore.com\/#\/schema\/logo\/image\/","url":"https:\/\/unrostore.com\/wp-content\/uploads\/2022\/05\/Logo-UNRO.png","contentUrl":"https:\/\/unrostore.com\/wp-content\/uploads\/2022\/05\/Logo-UNRO.png","width":605,"height":179,"caption":"UNRO"},"image":{"@id":"https:\/\/unrostore.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/unrostore.com\/de-at\/wp-json\/wp\/v2\/product\/4299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unrostore.com\/de-at\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/unrostore.com\/de-at\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unrostore.com\/de-at\/wp-json\/wp\/v2\/media\/6741"}],"wp:attachment":[{"href":"https:\/\/unrostore.com\/de-at\/wp-json\/wp\/v2\/media?parent=4299"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/unrostore.com\/de-at\/wp-json\/wp\/v2\/product_brand?post=4299"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/unrostore.com\/de-at\/wp-json\/wp\/v2\/product_cat?post=4299"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/unrostore.com\/de-at\/wp-json\/wp\/v2\/product_tag?post=4299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}